{"id":7652,"date":"2023-12-27T22:32:27","date_gmt":"2023-12-27T21:32:27","guid":{"rendered":"https:\/\/hotelvisavis.net\/hotel\/"},"modified":"2026-02-11T11:21:16","modified_gmt":"2026-02-11T10:21:16","slug":"hotel-zentrum-triest","status":"publish","type":"page","link":"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/","title":{"rendered":"Hotel"},"content":{"rendered":"<div  class=\"grids-section content-crossed-line grids-is-advanced\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:1\/13;--_ga-row:1\/7;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<p class=\"has-text-align-center\">Ein Ort, an dem Innovation und Tradition in einer raffinierten Schatulle aus Kristall und Holz zusammenkommen. Hier beleuchtet die Transparenz des Lichts die von der Natur geschaffenen warmen Farben.\n        <\/p>\n\n<\/div>\n<\/div><\/div>\n\n\n<div class=\"wp-block-group divider animated slideInLeft\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"has-text-align-center\">Eine raffinierte Schatulle\n        <\/p>\n<\/div><\/div>\n\n\n<div  id=\"servizi\" class=\"grids-section services-box-row grids-is-advanced alignwide\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:1\/13;--_ga-row:1\/7;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<p class=\"has-text-align-center counter-h\">UNSERE DIENSTLEISTUNGEN\n        <\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column animated fadeInUp has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#f5f5f5\">\n<i class=\"fa-thin fa-door-open\"><\/i>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">NACHTPORTIER\n        <\/h3>\n\n\n\n<p class=\"has-text-align-center\">Unser Nachtportier bietet Ihnen professionelle und diskrete Hilfe w\u00e4hrend der Nachtstunden.\n        <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column animated fadeInUp delay-100ms has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#f5f5f5\">\n<i class=\"fa-thin fa-suitcase\"><\/i>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">24-STUNDEN-PORTIER\n        <\/h3>\n\n\n\n<p class=\"has-text-align-center\">Von der Ankunft bis zur Abreise k\u00fcmmert sich unser Portier mit Hingabe um den Gep\u00e4cktransport.\n        <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column animated fadeInUp delay-200ms has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#f5f5f5\">\n<i class=\"fa-thin fa-garage-car\"><\/i>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">VALET PARKING<\/h3>\n\n\n\n<p class=\"has-text-align-center\">Abhol- und Bringservice\n        <br>f\u00fcr Autos.\n        <\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column animated fadeInUp has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#f5f5f5\">\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"43\" height=\"38\" fill=\"none\"><g clip-path=\"url(#a)\"><mask id=\"b\" style=\"mask-type:luminance\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"43\" height=\"38\"><path d=\"M42.957 0H0v37.776h42.957V0Z\" fill=\"#fff\"><\/path><\/mask><g mask=\"url(#b)\" fill=\"#625D57\"><path d=\"M32.602 31.357c-.083-.092-.16-.189-.25-.298.116-.112.213-.209.313-.301.963-.881 1.929-1.761 2.891-2.643.442-.404.452-.679.046-1.129-.494-.545-.989-1.088-1.487-1.63-.403-.438-.68-.449-1.129-.038-.428.391-.85.789-1.247 1.159l-.924-1.035c.417-.377.862-.773 1.299-1.176.388-.359.403-.656.05-1.047-.499-.557-1.005-1.108-1.51-1.659-.424-.461-.692-.474-1.157-.05-.965.879-1.931 1.757-2.889 2.644-.1.092-.144.242-.215.364l-.18-.077c-1.714-1.883-4.388-4.726-6.15-6.656.112-.107.225-.211.337-.32.758-.728.913-1.815.442-2.729-.465-.901-1.473-1.432-2.481-1.202-.486.111-.93.405-1.368.604l-1.13-1.23c3.929-1.24 5.513-5.575 3.905-8.873-.781-1.602-2.005-2.734-3.693-3.307-2.234-.76-4.284-.313-6.142 1.085C7.647-.584 4.355-.437 2.328 1.28 1.247 2.196.598 3.363.418 4.763c-.217 1.69.29 3.176 1.421 4.46C.693 10.442.06 11.86 0 13.506l1.203.055c.1-1.486.658-2.711 1.733-3.689.561-.511.563-.761-.006-1.292-1.797-1.678-1.786-4.558.024-6.234C4.773.663 7.664.893 9.19 2.844c.495.635.731.656 1.312.119a5.163 5.163 0 0 1 6.388-.49c2.001 1.351 2.823 3.9 1.93 6.14-.744 1.873-2.15 2.958-4.139 3.275-.294.048-.543.127-.657.43-.117.312.045.533.242.747.54.587 1.078 1.178 1.615 1.77.073.08.136.17.15.188l-1.624 1.494c-.561-.615-1.15-1.26-1.737-1.907-.2-.22-.4-.443-.74-.361-.349.083-.445.356-.522.672-.563 2.31-2.56 3.924-4.91 3.984-2.336.059-4.408-1.473-5.083-3.757-.027-.091-.067-.18-.106-.284l-1.178.28c.808 2.726 2.51 4.48 5.296 4.874 3.23.457 5.494-1.036 6.89-3.835l1.168 1.288c-1.013 1.083-1.133 2.335-.29 3.331.865 1.022 2.065 1.056 3.615.04.07.112.132.257.233.367 4.917 5.399 9.838 10.793 14.76 16.189.444.487.702.5 1.18.066.74-.675 1.48-1.35 2.218-2.026.476-.436.485-.697.041-1.184-.878-.966-1.76-1.93-2.639-2.896l-.001-.002Zm-2.547-8.55.835.937c-.37.335-.79.712-1.207 1.093-.518.474-.528.718-.057 1.236.486.533.97 1.068 1.46 1.599.375.406.664.422 1.071.051.438-.4.867-.81 1.312-1.226l.849 1.017-2.785 2.545a25674.2 25674.2 0 0 1-4.305-4.721l2.827-2.53v-.001Zm-14.268-2.762c-.542.49-1.217.484-1.655-.004-.428-.477-.375-1.145.144-1.623 1.222-1.123 2.442-2.248 3.682-3.351.222-.198.536-.293.675-.366.613.02 1.012.297 1.164.714.169.463.075.88-.281 1.217-.571.54-1.157 1.063-1.736 1.593-.665.607-1.326 1.216-1.993 1.82Zm16.686 16.18L22.355 25.13a.825.825 0 0 1-.096-.09 1.484 1.484 0 0 1-.103-.127 2.207 2.207 0 0 1-.05-.04.68.68 0 0 1-.08-.077 2.41 2.41 0 0 1-.144-.186l-4.212-4.618c.072-.07.168-.168.27-.26.414-.381.832-.758 1.249-1.136 1.18 1.291 2.414 2.64 3.677 4.015a.49.49 0 0 1 .079.086l.166.18c.341.324.663.672.957 1.042 3.383 3.68 6.889 7.484 9.979 10.87l-1.574 1.435v.001Z\"><\/path><path d=\"M6.203 17.07c-1.823-.088-3.251-1.668-3.164-3.501a3.35 3.35 0 0 1 3.519-3.185 3.353 3.353 0 0 1 3.165 3.5 3.357 3.357 0 0 1-3.52 3.186Zm.053-1.217c1.168.068 2.188-.839 2.25-2a2.134 2.134 0 0 0-2-2.252 2.137 2.137 0 0 0-2.25 2 2.136 2.136 0 0 0 1.999 2.252ZM13.844 10.106a3.355 3.355 0 0 1-3.179-3.526c.092-1.827 1.666-3.248 3.502-3.16a3.35 3.35 0 0 1 3.179 3.524c-.092 1.826-1.673 3.254-3.502 3.162Zm.042-1.217c1.168.065 2.186-.845 2.245-2.007a2.133 2.133 0 0 0-2.007-2.246 2.137 2.137 0 0 0-2.244 2.007 2.136 2.136 0 0 0 2.006 2.245v.001ZM8.273 5.606a2.438 2.438 0 0 1-2.568 2.3 2.437 2.437 0 0 1-2.291-2.54 2.437 2.437 0 0 1 2.548-2.322 2.443 2.443 0 0 1 2.311 2.56v.002Zm-3.642-.182A1.22 1.22 0 0 0 5.783 6.69a1.226 1.226 0 0 0 1.275-1.143 1.221 1.221 0 0 0-1.171-1.285 1.22 1.22 0 0 0-1.255 1.163H4.63ZM22.153 24.911l-.047-.038a.688.688 0 0 1-.08-.076c-.077-.088-.145-.184-.212-.28l-.037-.048a.583.583 0 0 1-.099-.098.468.468 0 0 1-.112-.126.464.464 0 0 1-.082-.083 97980.59 97980.59 0 0 1-11 12.063L8.91 34.79l11.13-12.199c-.341-.285-.518-.644-.808-.886-1.755 1.928-.71.782-2.49 2.737l-.18.076c-.07-.122-.115-.272-.214-.363-.958-.888-1.924-1.767-2.89-2.645-.464-.424-.732-.411-1.155.05-.505.551-1.012 1.102-1.512 1.659-.352.392-.337.688.051 1.047.437.404.881.8 1.299 1.177l-.925 1.034c-.397-.37-.818-.768-1.246-1.16-.448-.41-.725-.399-1.129.04-.497.54-.993 1.084-1.487 1.63-.407.45-.396.724.046 1.128.962.883 1.928 1.762 2.89 2.643.102.092.199.19.314.3-.091.11-.167.208-.25.299-.88.965-1.76 1.929-2.639 2.895-.444.488-.434.748.041 1.184.739.676 1.478 1.352 2.219 2.026.478.436.736.423 1.18-.066 3.732-4.09 7.461-8.182 11.191-12.274a.811.811 0 0 1-.088-.081 1.373 1.373 0 0 1-.105-.13ZM8.638 27.514l.85-1.018c.444.417.873.826 1.31 1.226.408.372.698.355 1.072-.051.49-.53.974-1.065 1.46-1.599.472-.517.461-.762-.057-1.236-.417-.38-.836-.757-1.207-1.093l.835-.937 2.827 2.53-4.305 4.722a5155.32 5155.32 0 0 1-2.785-2.545ZM41.542 15.146c-.675 2.284-2.747 3.816-5.084 3.757-2.348-.059-4.346-1.674-4.909-3.984-.077-.315-.174-.59-.523-.672-.34-.082-.54.14-.74.361-.586.647-1.176 1.292-1.736 1.907l-1.625-1.494c.014-.018.078-.107.151-.188.537-.592 1.074-1.183 1.615-1.77.197-.214.359-.434.242-.746-.114-.303-.363-.384-.657-.43-1.99-.318-3.395-1.403-4.14-3.276-.891-2.24-.07-4.789 1.93-6.14a5.163 5.163 0 0 1 6.389.49c.582.537.816.516 1.312-.119 1.525-1.951 4.417-2.181 6.236-.497 1.81 1.677 1.821 4.556.024 6.234-.568.53-.567.781-.006 1.292 1.074.978 1.632 2.203 1.733 3.69l1.203-.056c-.06-1.647-.693-3.063-1.84-4.285 1.13-1.284 1.638-2.77 1.421-4.459-.18-1.4-.828-2.566-1.91-3.483-2.026-1.718-5.318-1.864-7.605.533C31.165.413 29.113-.032 26.88.726c-1.687.573-2.91 1.706-3.692 3.307-1.609 3.298-.024 7.633 3.904 8.873-.383.417-.774.844-1.13 1.23-.437-.199-.882-.492-1.367-.603-1.008-.23-2.016.3-2.482 1.201-.471.914-.315 2 .442 2.73.804.773 1.641 1.511 2.463 2.266.1.092.196.19.268.26-.801.88-1.602 1.757-2.403 2.635.032.03.055.064.075.102.287.26.554.542.81.835l2.147-2.356c.1-.11.163-.256.232-.368 1.55 1.017 2.75.982 3.615-.04.844-.995.723-2.248-.29-3.33l1.169-1.288c1.396 2.798 3.66 4.293 6.89 3.835 2.785-.394 4.488-2.149 5.296-4.874l-1.178-.28c-.04.104-.079.191-.106.284v.001Zm-12.716 4.895c-.438.487-1.114.493-1.655.003-.667-.603-1.329-1.212-1.993-1.819-.58-.53-1.165-1.053-1.736-1.592-.357-.337-.45-.755-.282-1.218.152-.417.551-.694 1.165-.713.138.072.452.167.675.365 1.24 1.103 2.46 2.228 3.682 3.351.519.478.572 1.146.144 1.623Z\"><\/path><path d=\"M33.234 13.884a3.353 3.353 0 0 1 3.165-3.5 3.35 3.35 0 0 1 3.518 3.185c.088 1.833-1.34 3.413-3.163 3.5a3.357 3.357 0 0 1-3.52-3.184Zm5.466-.283a2.136 2.136 0 0 0-2.25-2 2.134 2.134 0 0 0-2 2.252c.062 1.161 1.082 2.069 2.25 2a2.136 2.136 0 0 0 2-2.252ZM25.61 6.944a3.35 3.35 0 0 1 3.179-3.525c1.836-.087 3.41 1.334 3.502 3.16a3.355 3.355 0 0 1-3.178 3.527c-1.83.092-3.41-1.336-3.502-3.162Zm5.466-.301a2.137 2.137 0 0 0-2.244-2.007 2.133 2.133 0 0 0-2.006 2.246c.058 1.161 1.076 2.072 2.244 2.007a2.136 2.136 0 0 0 2.006-2.245v-.001ZM36.994 3.044a2.436 2.436 0 0 1 2.548 2.322 2.438 2.438 0 0 1-2.29 2.54 2.439 2.439 0 0 1-2.57-2.3 2.443 2.443 0 0 1 2.312-2.561Zm.076 1.217a1.221 1.221 0 0 0-1.17 1.285 1.225 1.225 0 0 0 1.274 1.143 1.22 1.22 0 0 0 1.152-1.266A1.22 1.22 0 0 0 37.07 4.26h-.001ZM21.167 19.093l1.598-1.725.761.77-1.64 1.73\"><\/path><\/g><\/g><defs><clippath id=\"a\"><path fill=\"#fff\" d=\"M0 0h43v37.84H0z\"><\/path><\/clippath><\/defs><\/svg>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">CONCIERGE\n        <\/h3>\n\n\n\n<p class=\"has-text-align-center\">Wir bieten einen st\u00e4ndigen Service, um unseren G\u00e4sten einen angenehmen Aufenthalt zu gew\u00e4hrleisten.\n        <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column animated fadeInUp delay-100ms has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#f5f5f5\">\n<i class=\"fa-thin fa-baby-carriage\"><\/i>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">BABYSITTING\n        <\/h3>\n\n\n\n<p class=\"has-text-align-center\">Wir k\u00fcmmern uns um Ihre Kleinen mit unserem professionellen und zuverl\u00e4ssigen Babysitter-Service.\n        <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column animated fadeInUp delay-200ms has-background is-layout-flow wp-block-column-is-layout-flow\" style=\"background-color:#f5f5f5\">\n<i class=\"fa-thin fa-washing-machine\"><\/i>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\">W\u00c4SCHEREISERVICE\n        <\/h3>\n\n\n\n<p class=\"has-text-align-center\">Professionelle W\u00e4sche und Pflege Ihrer Kleidungsst\u00fccke.\n        <\/p>\n<\/div>\n<\/div>\n\n<\/div>\n<\/div><\/div>\n\n<div  id=\"colazione\" class=\"grids-section three-image-row grids-is-advanced alignwide\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area content animated fadeInRight\" style=\"--_ga-column:8\/13;--_ga-row:1\/4;--_ga-va:center;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<p class=\"counter-h\">AM MORGEN ERKENNT MAN DEN TAG\n        <\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\">S\u00fc\u00dfes oder salziges Fr\u00fchst\u00fcck\n        <\/h2>\n\n\n\n<p>Beginnen Sie den Tag, <strong>indem Sie Ihren Gaumen verw\u00f6hnen<\/strong>! Mit frischen Croissants, aromatischem Kaffee, frisch gebackenen Kuchen, Eiern, Wurstwaren und vielem mehr. Im Hotel Vis a Vis verw\u00f6hnen wir Sie vom ersten Moment des Tages an.\n        <\/p>\n\n\n\n<div class=\"wp-block-group is-horizontal is-content-justification-left is-nowrap is-layout-flex wp-container-core-group-is-layout-332b5c8f wp-block-group-is-layout-flex\">\n<i class=\"fa-thin fa-mug-saucer\" style=\"color: #625d57;\"><\/i>\n\n\n\n<p>S\u00fc\u00dfes oder salziges Fr\u00fchst\u00fcck\n        <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-group is-nowrap is-layout-flex wp-container-core-group-is-layout-ad2f72ca wp-block-group-is-layout-flex\">\n<i class=\"fa-thin fa-wheat-slash\" style=\"color: #625d57;\"><\/i>\n\n\n\n<p>Wir haben eine gro\u00dfe Auswahl an glutenfreien Lebensmitteln, die f\u00fcr jede Di\u00e4t geeignet sind\n        <\/p>\n<\/div>\n\n<\/div>\n\n<div class=\"grids-area image-big animated fadeInLeft\" style=\"--_ga-column:1\/8;--_ga-row:2\/7;--_ga-va:flex-end;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-large full-width\"><img loading=\"lazy\" decoding=\"async\" width=\"902\" height=\"1024\" src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-902x1024.jpg\" alt=\"Fr\u00fchst\u00fcck mit Schale mit Obst, M\u00fcsli, Brot und Messer auf dem Tischtuch.\n        \" class=\"wp-image-7174\" srcset=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-902x1024.jpg 902w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-264x300.jpg 264w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-768x872.jpg 768w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-500x568.jpg 500w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-800x908.jpg 800w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata.jpg 960w\" sizes=\"auto, (max-width: 902px) 100vw, 902px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"grids-area image animated fadeInRight delay-100ms\" style=\"--_ga-column:7\/10;--_ga-row:4\/7;--_ga-va:flex-end;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-large full-width\"><img loading=\"lazy\" decoding=\"async\" width=\"902\" height=\"1024\" src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-1-902x1024.jpg\" alt=\"Eine Person fr\u00fchst\u00fcckt mit Obst, Orangensaft und verschiedenem Geb\u00e4ck.\n        \" class=\"wp-image-7177\" srcset=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-1-902x1024.jpg 902w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-1-264x300.jpg 264w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-1-768x872.jpg 768w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-1-500x568.jpg 500w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-1-800x908.jpg 800w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-1.jpg 960w\" sizes=\"auto, (max-width: 902px) 100vw, 902px\" \/><\/figure>\n\n<\/div>\n\n<div class=\"grids-area image animated fadeInRight delay-200ms\" style=\"--_ga-column:10\/13;--_ga-row:4\/7;--_ga-va:flex-end;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-large full-width\"><img loading=\"lazy\" decoding=\"async\" width=\"902\" height=\"1024\" src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-2-902x1024.jpg\" alt=\"Sala colazione moderna con buffet assortito e tavoli apparecchiati in hotel.\n        \" class=\"wp-image-7180\" srcset=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-2-902x1024.jpg 902w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-2-264x300.jpg 264w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-2-768x872.jpg 768w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-2-500x568.jpg 500w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-2-800x908.jpg 800w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Colazione-dolce-o-salata-2.jpg 960w\" sizes=\"auto, (max-width: 902px) 100vw, 902px\" \/><\/figure>\n\n<\/div>\n<\/div><\/div>\n\n<div  class=\"grids-section grids-is-advanced alignfull\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:1\/13;--_ga-row:1\/7;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n    <!-- GALLERY (Swiper) -->\n    <div class=\"slider-gallery-wrapper\" id=\"customGallery_1\">\n        <div class=\"swiper-wrapper\">\n                                            <div class=\"slider-gallery-single-image swiper-slide\">\n                    <figure class=\"full-width slider-gallery\">\n                        <img decoding=\"async\"\n                            src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel-1.webp\"\n                            alt=\"Colazione hotel, caraffe latte, succhi Zuegg, insalata verde, confezioni formaggio spalmabile.\"\n                            loading=\"lazy\"\n                        \/>\n                    <\/figure>\n                <\/div>\n                                            <div class=\"slider-gallery-single-image swiper-slide\">\n                    <figure class=\"full-width slider-gallery\">\n                        <img decoding=\"async\"\n                            src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel-2.webp\"\n                            alt=\"Una donna elegante e sorridente si serve da un ricco buffet di colazione in un hotel luminoso, scegliendo frutta e pasticceria.\"\n                            loading=\"lazy\"\n                        \/>\n                    <\/figure>\n                <\/div>\n                                            <div class=\"slider-gallery-single-image swiper-slide\">\n                    <figure class=\"full-width slider-gallery\">\n                        <img decoding=\"async\"\n                            src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel-3.webp\"\n                            alt=\"Due donne si godono una tranquilla colazione in hotel, sedute al tavolo, chiacchierando serenamente in una sala luminosa.\"\n                            loading=\"lazy\"\n                        \/>\n                    <\/figure>\n                <\/div>\n                    <\/div>\n\n        <!-- FRECCE (gallery principale) -->\n        <div class=\"swiper-button-prev\"><\/div>\n        <div class=\"swiper-button-next\"><\/div>\n\n        <div class=\"slider-list-navigation\">\n            <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\t<\/div>\n\n    <!-- LIGHTBOX (solo Swiper, nessuna libreria extra) -->\n    <div class=\"swiper-lightbox\" id=\"customGallery_1__lightbox\" aria-hidden=\"true\">\n        <button type=\"button\" class=\"swiper-lightbox__close\" aria-label=\"Chiudi\">\u00d7<\/button>\n\n        <div class=\"swiper-lightbox__inner\">\n            <div class=\"swiper swiper-lightbox__swiper\" id=\"customGallery_1__lightbox_swiper\">\n                <div class=\"swiper-wrapper\">\n                                                                    <div class=\"swiper-slide\">\n                            <div class=\"swiper-lightbox__slide\">\n                                <img decoding=\"async\"\n                                    src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel-1.webp\"\n                                    alt=\"Colazione hotel, caraffe latte, succhi Zuegg, insalata verde, confezioni formaggio spalmabile.\"\n                                \/>\n                            <\/div>\n                        <\/div>\n                                                                    <div class=\"swiper-slide\">\n                            <div class=\"swiper-lightbox__slide\">\n                                <img decoding=\"async\"\n                                    src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel-2.webp\"\n                                    alt=\"Una donna elegante e sorridente si serve da un ricco buffet di colazione in un hotel luminoso, scegliendo frutta e pasticceria.\"\n                                \/>\n                            <\/div>\n                        <\/div>\n                                                                    <div class=\"swiper-slide\">\n                            <div class=\"swiper-lightbox__slide\">\n                                <img decoding=\"async\"\n                                    src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel-3.webp\"\n                                    alt=\"Due donne si godono una tranquilla colazione in hotel, sedute al tavolo, chiacchierando serenamente in una sala luminosa.\"\n                                \/>\n                            <\/div>\n                        <\/div>\n                                    <\/div>\n\n                <!-- FRECCE (lightbox) -->\n                <div class=\"swiper-button-prev\"><\/div>\n                <div class=\"swiper-button-next\"><\/div>\n\n                <!-- PALLINI (lightbox) -->\n                <div class=\"swiper-pagination\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<script type=\"text\/javascript\">\njQuery(document).ready(function () {\n\n    var galleryId   = '#customGallery_1';\n    var lightboxId  = '#customGallery_1__lightbox';\n    var lightboxSw  = '#customGallery_1__lightbox_swiper';\n\n    \/\/ Swiper principale\n    var mainSwiper = new Swiper(galleryId, {\n        slidesPerView: 'auto',\n        spaceBetween: 0,\n        loop: true,\n        centeredSlides: true,\n        autoplay: {\n            delay: 5500,\n            disableOnInteraction: true,\n        },\n        navigation: {\n            nextEl: galleryId + ' .swiper-button-next',\n            prevEl: galleryId + ' .swiper-button-prev'\n        },\n        pagination: {\n            el: galleryId + ' .slider-list-navigation .swiper-pagination',\n            clickable: true\n        },\n    });\n\n    \/\/ Swiper del lightbox (creato al primo open)\n    var lbSwiper = null;\n\n    function openLightbox(startIndex) {\n        var $lb = jQuery(lightboxId);\n\n        $lb.addClass('is-open').attr('aria-hidden', 'false');\n        jQuery('body').addClass('swiper-lightbox-open');\n\n        if (!lbSwiper) {\n            lbSwiper = new Swiper(lightboxSw, {\n                slidesPerView: 1,\n                loop: true,\n                centeredSlides: true,\n                keyboard: {\n                    enabled: true,\n                    onlyInViewport: false\n                },\n                navigation: {\n                    nextEl: lightboxSw + ' .swiper-button-next',\n                    prevEl: lightboxSw + ' .swiper-button-prev'\n                },\n                pagination: {\n                    el: lightboxSw + ' .swiper-pagination',\n                    clickable: true\n                }\n            });\n        }\n\n        \/\/ Con loop true, usiamo slideToLoop per posizionare correttamente\n        if (typeof startIndex === 'number') {\n            lbSwiper.slideToLoop(startIndex, 0);\n        }\n    }\n\n    function closeLightbox() {\n        var $lb = jQuery(lightboxId);\n        $lb.removeClass('is-open').attr('aria-hidden', 'true');\n        jQuery('body').removeClass('swiper-lightbox-open');\n    }\n\n    \/\/ Click sulla gallery: apri lightbox alla slide corretta\n    \/\/ Con loop, Swiper mette data-swiper-slide-index sulle slide cliccate (incluse le duplicate)\n    mainSwiper.on('click', function(swiper) {\n        if (!swiper.clickedSlide) return;\n\n        var realIndexAttr = swiper.clickedSlide.getAttribute('data-swiper-slide-index');\n        var realIndex = (realIndexAttr !== null) ? parseInt(realIndexAttr, 10) : swiper.clickedIndex;\n\n        if (!isNaN(realIndex)) {\n            openLightbox(realIndex);\n        }\n    });\n\n    \/\/ Chiudi: bottone X\n    jQuery(lightboxId + ' .swiper-lightbox__close').on('click', function(e){\n        e.preventDefault();\n        closeLightbox();\n    });\n\n    \/\/ Chiudi: click fuori dall'immagine (overlay)\n    jQuery(lightboxId).on('click', function(e){\n\n        \/\/ Se clicco sull'immagine, NON chiudo\n        if (jQuery(e.target).closest('.swiper-lightbox__slide img').length) return;\n\n        \/\/ Se clicco su controlli UI (frecce, pagination, close), NON chiudo\n        if (jQuery(e.target).closest('.swiper-button-prev, .swiper-button-next, .swiper-pagination, .swiper-lightbox__close').length) return;\n\n        \/\/ Altrimenti (overlay \/ zone vuote) chiudo\n        closeLightbox();\n    });\n\n    \/\/ Chiudi: ESC\n    jQuery(document).on('keydown', function(e){\n        if (e.key === 'Escape' && jQuery(lightboxId).hasClass('is-open')) {\n            closeLightbox();\n        }\n    });\n\n});\n<\/script>\n\n<style>\n\/* blocca scroll quando la lightbox \u00e8 aperta *\/\nbody.swiper-lightbox-open {\n  overflow: hidden;\n}\n\n\/* overlay *\/\n.swiper-lightbox {\n  position: fixed;\n  inset: 0;\n  z-index: 99999;\n  display: none;\n  background: rgba(0,0,0,.92);\n}\n\n\/* visibile *\/\n.swiper-lightbox.is-open {\n  display: block;\n}\n\n\/* contenitore interno *\/\n.swiper-lightbox__inner {\n  width: 100%;\n  height: 100%;\n  display: flex;\n  align-items: center;\n  justify-content: center;\n}\n\n\/* swiper fullscreen (lightbox) *\/\n.swiper-lightbox__swiper {\n  width: 100%;\n  height: 100%;\n}\n\n\/* slide (lightbox) *\/\n.swiper-lightbox__slide {\n  width: 100%;\n  height: 100%;\n  display: flex;\n  align-items: center;\n  justify-content: center;\n}\n\n.swiper-lightbox__slide img {\n  max-width: 95vw;\n  max-height: 90vh;\n  width: auto;\n  height: auto;\n  object-fit: contain;\n}\n\n\/* bottone chiusura *\/\n.swiper-lightbox__close {\n  position: absolute;\n  top: 16px;\n  right: 16px;\n  z-index: 100000;\n  width: 44px;\n  height: 44px;\n  border: 0;\n  border-radius: 999px;\n  background: rgba(255,255,255,.12);\n  color: #fff;\n  font-size: 28px;\n  line-height: 44px;\n  cursor: pointer;\n}\n\n\/* navigazione lightbox *\/\n.swiper-lightbox .swiper-button-prev,\n.swiper-lightbox .swiper-button-next {\n  color: #fff;\n  padding: 30px;\n}\n\n.swiper-lightbox .swiper-pagination-bullet {\n  background: rgba(255,255,255,.6);\n  opacity: 1;\n}\n\n.swiper-lightbox .swiper-pagination-bullet-active {\n  background: #fff;\n}\n\n\/* TWEAK visual gi\u00e0 presenti *\/\nbutton.swiper-lightbox__close {\n  position: absolute !important;\n  color: white !important;\n  font-size: 50px !important;\n  font-weight: 400 !important;\n}\n\n\/* abilita click sull'immagine in gallery *\/\n.slider-gallery-single-image.swiper-slide img{\n  pointer-events: all !important;\n}\n\n\/* FRECCE in gallery principale *\/\n.slider-gallery-wrapper .swiper-button-prev,\n.slider-gallery-wrapper .swiper-button-next {\n  color: #fff;      \/* cambia se vuoi *\/\n  padding: 30px;\n}\n\n\/* (opzionale) ombra per leggibilit\u00e0 frecce su immagini chiare *\/\n.slider-gallery-wrapper .swiper-button-prev:after,\n.slider-gallery-wrapper .swiper-button-next:after {\n  text-shadow: 0 2px 10px rgba(0,0,0,.35);\n}\n\n\n\n\n\n\n\n\n\n\n\n\n\n\/* --- PAGINATION: forzo visibilit\u00e0 ovunque --- *\/\n.slider-gallery-wrapper,\n.swiper-lightbox__swiper {\n  position: relative;\n}\n\n\/* PALLINI nella gallery (fuori dal lightbox) *\/\n.slider-gallery-wrapper .slider-list-navigation {\n  position: absolute;\n  left: 0;\n  right: 0;\n  bottom: 0px;\n  z-index: 50;\n  display: flex !important;\n  justify-content: center;\n  pointer-events: none; \/* non blocca click\/drag *\/\n}\n\n.slider-gallery-wrapper .slider-list-navigation .swiper-pagination {\n  position: static !important;\n  display: block !important;\n  opacity: 1 !important;\n  visibility: visible !important;\n  pointer-events: auto;\n}\n\n\/* PALLINI nel lightbox *\/\n.swiper-lightbox .swiper-pagination {\n  position: absolute !important;\n  left: 0;\n  right: 0;\n  bottom: 18px !important;\n  z-index: 100001 !important;\n  display: flex !important;\n  justify-content: center;\n  opacity: 1 !important;\n  visibility: visible !important;\n}\n\n\/* BULLETS: dimensioni e visibilit\u00e0 *\/\n.slider-gallery-wrapper .swiper-pagination-bullet,\n.swiper-lightbox .swiper-pagination-bullet {\n  width: 10px !important;\n  height: 10px !important;\n  opacity: 1 !important;\n  display: inline-block !important;\n  margin: 0 6px !important;\n}\n\n\/* colori (puoi cambiarli) *\/\n.slider-gallery-wrapper .swiper-pagination-bullet, .swiper-lightbox .swiper-pagination-bullet {\n    background: rgb(154 154 154 \/ 60%) !important;\n    border-color: rgb(154 154 154 \/ 30%) !important;\n}\n\n.slider-gallery-wrapper .swiper-pagination-bullet-active,\n.swiper-lightbox .swiper-pagination-bullet-active {\n  background: #fff !important;\n}\n\n\/* (opzionale) se in gallery i pallini finiscono \"sotto\" e non li vedi mai, crea spazio *\/\n.slider-gallery-wrapper {\n  padding-bottom: 34px;\n}\n\nbutton.swiper-lightbox__close:before {\n    width: 100% !important;\n}\n<\/style>\n\n\n<\/div>\n<\/div><\/div>\n\n<div  id=\"pet-friendly\" class=\"grids-section content-image-over grids-is-advanced alignwide\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:transparent none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:transparent none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:transparent none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area content animated fadeInLeft\" style=\"--_ga-column:1\/8;--_ga-row:1\/7;--_ga-va:center;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:#f5f5f5 none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:#f5f5f5 none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:#f5f5f5 none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<p class=\"counter-h\">F\u00dcR TIERLIEBHABER\n        <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tierfreundliche Hotels und Aparthotel<\/h2>\n\n\n\n<p>Alle Vierbeiner sind im Vis a Vis Hotel &amp; Aparthotel willkommen! <br>Bitte teilen Sie uns bei der Buchung mit, dass Sie Ihren Hund mitbringen werden, damit wir Ihnen maximalen Komfort bieten k\u00f6nnen. Wir berechnen eine Geb\u00fchr von 20 Euro pro Tag (pro Tier).<\/p>\n\n\n\n<p>Beantragen Sie die folgenden Dienstleistungen 24 Stunden im Voraus:\n        <\/p>\n\n\n\n<div class=\"wp-block-columns columns-icons is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<i class=\"fa-thin fa-paw-simple\"><\/i>\n\n\n\n<p class=\"has-text-align-center\">Hundebetreuung\n        <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<i class=\"fa-thin fa-dog-leashed\"><\/i>\n\n\n\n<p class=\"has-text-align-center\">Hundeausf\u00fchrservice\n        <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<i class=\"fa-thin fa-pump-soap\"><\/i>\n\n\n\n<p class=\"has-text-align-center\">Pflege\n        <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<i class=\"fa-thin fa-taxi\"><\/i>\n\n\n\n<p class=\"has-text-align-center\">Taxidienst \u201eHund an Bord\u201c\n        <\/p>\n<\/div>\n<\/div>\n\n<\/div>\n\n<div class=\"grids-area image animated fadeInRight\" style=\"--_ga-column:7\/13;--_ga-row:1\/7;--_ga-va:center;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n\n<figure class=\"wp-block-image size-full full-width\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"773\" src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Pet-Friendly.png\" alt=\"wei\u00dfer Hund schl\u00e4ft eingewickelt in weiche Decken\n        \" class=\"wp-image-7195\" srcset=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Pet-Friendly.png 632w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Pet-Friendly-245x300.png 245w, https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Pet-Friendly-500x612.png 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/figure>\n\n<\/div>\n<\/div><\/div>\n\n<div  class=\"grids-section no-background-mobile grids-is-advanced alignwide\" style=\"--_gs-gap-desktop:0px 0px;--_gs-m-desktop:0 0 0 0;--_gs-p-desktop:0 0 0 0;--_gs-bg-desktop:#f5f5f5 none;--_gs-bg-xp-desktop:0px;--_gs-zi-desktop:auto;--_gs-d-desktop:block;--_gs-mw-desktop:calc(100% - 0 - 0);--_gs-gap-tablet:0px 0px;--_gs-m-tablet:0 0 0 0;--_gs-p-tablet:0 0 0 0;--_gs-bg-tablet:#f5f5f5 none;--_gs-bg-xp-tablet:0px;--_gs-zi-tablet:auto;--_gs-d-tablet:block;--_gs-mw-tablet:calc(100% - 0 - 0);--_gs-gap-mobile:0px 0px;--_gs-m-mobile:0 0 0 0;--_gs-p-mobile:0 0 0 0;--_gs-bg-mobile:#f5f5f5 none;--_gs-bg-xp-mobile:0px;--_gs-zi-mobile:auto;--_gs-d-mobile:block;--_gs-mw-mobile:calc(100% - 0 - 0);--_gs-columns:12;--_gs-rows:6\"><div class=\"grids-s-w_i\">\n<div class=\"grids-area\" style=\"--_ga-column:1\/13;--_ga-row:1\/7;--_ga-va:center;--_ga-m-desktop:0 0 0 0;--_ga-p-desktop:0 0 0 0;--_ga-bg-desktop:transparent none;--_ga-zi-desktop:auto;--_ga-d-desktop:flex;--_ga-mw-desktop:calc(100% - 0 - 0);--_ga-m-tablet:0 0 0 0;--_ga-p-tablet:0 0 0 0;--_ga-bg-tablet:transparent none;--_ga-zi-tablet:auto;--_ga-d-tablet:flex;--_ga-mw-tablet:calc(100% - 0 - 0);--_ga-m-mobile:0 0 0 0;--_ga-p-mobile:0 0 0 0;--_ga-bg-mobile:transparent none;--_ga-zi-mobile:auto;--_ga-d-mobile:flex;--_ga-mw-mobile:calc(100% - 0 - 0)\">\n    <div class=\"vertical-slider-wrapper\" id=\"verticalSlider_2\">\n        <div class=\"slider\">\n            <div class=\"swiper-wrapper\">\n                                                        <div class=\"swiper-slide bigger-image\">\n                        <figure class=\"full-width animated fadeInLeft\">\n                            <img decoding=\"async\" src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2025\/06\/DELUXE-300x200-1.jpg\" alt=\"\" \/>\n                        <\/figure>\n                        \n                        <div class=\"content animated fadeInRight\">\n                            <p class=\"counter-h\" counter-group=\"verticalSlider_2\">UNSERE EINZIGARTIGKEIT        <\/p>\n                                                            <h2>ZIMMER        <\/h2>\n                                                        <p><a href=\"https:\/\/hotelvisavis.net\/de\/ubernachten-in-triest\/\">S\u00fc\u00dfe Tr\u00e4ume<\/a><\/p>\n                        <\/div>\n                    <\/div>\n                                                                            <div class=\"swiper-slide bigger-image\">\n                        <figure class=\"full-width \">\n                            <img decoding=\"async\" src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/La-magica-trieste.webp\" alt=\"Veduta aerea di Trieste al tramonto, con mare e architettura storica.\" \/>\n                        <\/figure>\n                        \n                        <div class=\"content \">\n                            <p class=\"counter-h\" counter-group=\"verticalSlider_2\">UNSERE EINZIGARTIGKEIT        <\/p>\n                                                            <h2>FOTOGALERIE        <\/h2>\n                                                        <p><a href=\"https:\/\/hotelvisavis.net\/de\/fotogalerie\/\">SCHAUEN SIE SICH DIE FOTOS AN<\/a><\/p>\n                        <\/div>\n                    <\/div>\n                                                                            <div class=\"swiper-slide bigger-image\">\n                        <figure class=\"full-width \">\n                            <img decoding=\"async\" src=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Harrys-1.webp\" alt=\"Tavolo rotondo elegante con luci soffuse, ombre artistiche, vino e pane.\" \/>\n                        <\/figure>\n                        \n                        <div class=\"content \">\n                            <p class=\"counter-h\" counter-group=\"verticalSlider_2\">UNSERE EINZIGARTIGKEIT        <\/p>\n                                                            <h2>Apartments        <\/h2>\n                                                        <p><a href=\"https:\/\/harrystrieste.it\/de\/\" target=\"_blank\">MEHR ERFAHREN<\/a><\/p>\n                        <\/div>\n                    <\/div>\n                                                <\/div>\n        <\/div>\n\n        <div class=\"slider-list-navigation\">\n            <div class=\"swiper-button-prev\"><\/div>\n            <div class=\"swiper-pagination\"><\/div>\n            <div class=\"swiper-button-next\"><\/div>\n        <\/div>\n    <\/div>\n\n\n<script type=\"text\/javascript\">\n    jQuery(document).ready(function () {\n        \/\/ initialize swiper when document ready\n\n        if (window.innerWidth <= 575) {\n            var verticalSlider_2 = new Swiper ('#verticalSlider_2 .slider', {\n                slidesPerView: 'auto',\n                pagination: {\n                    el: '#verticalSlider_2 .slider-list-navigation .swiper-pagination',\n                    type: \"fraction\"\n                },\n                navigation: {\n                    nextEl: '#verticalSlider_2 .slider-list-navigation .swiper-button-next',\n                    prevEl: '#verticalSlider_2 .slider-list-navigation .swiper-button-prev',\n                }\n            });\n\n            jQuery('#verticalSlider_2 .swiper-slide').each( function( i ) {\n                var photo = jQuery(this).find('figure');\n                var counter = jQuery(this).find('p.counter-h');\n                \n                counter.insertBefore(photo);\n            });\n        } else {\n            var verticalSlider_2 = new Swiper ('#verticalSlider_2 .slider', {\n                slidesPerView: 1,\n                direction: \"vertical\",\n                pagination: {\n                    el: '#verticalSlider_2 .slider-list-navigation .swiper-pagination',\n                    type: \"fraction\"\n                },\n                navigation: {\n                    nextEl: '#verticalSlider_2 .slider-list-navigation .swiper-button-next',\n                    prevEl: '#verticalSlider_2 .slider-list-navigation .swiper-button-prev',\n                }\n            });\n        }\n    });\n<\/script>\n\n<\/div>\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Eine raffinierte Schatulle<\/p>\n","protected":false},"author":1,"featured_media":7121,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-7652","page","type-page","status-publish","has-post-thumbnail","hentry","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hotel im Zentrum von Triest | Hotel Vis A&#039; Vis<\/title>\n<meta name=\"description\" content=\"Einzigartiges Erlebnis in Triest. \u00dcbernachten Sie im Herzen der Stadt im Hotel Vis A&#039; Vis. Entdecken Sie Komfort auf Knopfdruck!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hotel im Zentrum von Triest | Hotel Vis A&#039; Vis\" \/>\n<meta property=\"og:description\" content=\"Einzigartiges Erlebnis in Triest. \u00dcbernachten Sie im Herzen der Stadt im Hotel Vis A&#039; Vis. Entdecken Sie Komfort auf Knopfdruck!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/\" \/>\n<meta property=\"og:site_name\" content=\"Vis \u00e0 Vis\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Hotel.Duchi.Trieste\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T10:21:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1498\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/\",\"url\":\"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/\",\"name\":\"Hotel im Zentrum von Triest | Hotel Vis A' Vis\",\"isPartOf\":{\"@id\":\"https:\/\/hotelvisavis.net\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel.webp\",\"datePublished\":\"2023-12-27T21:32:27+00:00\",\"dateModified\":\"2026-02-11T10:21:16+00:00\",\"description\":\"Einzigartiges Erlebnis in Triest. \u00dcbernachten Sie im Herzen der Stadt im Hotel Vis A' Vis. Entdecken Sie Komfort auf Knopfdruck!\",\"breadcrumb\":{\"@id\":\"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/#primaryimage\",\"url\":\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel.webp\",\"contentUrl\":\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel.webp\",\"width\":2000,\"height\":1498,\"caption\":\"Vista aerea di una strada cittadina con parcheggio e edifici storici.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hotelvisavis.net\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hotel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hotelvisavis.net\/de\/#website\",\"url\":\"https:\/\/hotelvisavis.net\/de\/\",\"name\":\"Vis \u00e0 Vis\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/hotelvisavis.net\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hotelvisavis.net\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hotelvisavis.net\/de\/#organization\",\"name\":\"Vis \u00e0 Vis\",\"url\":\"https:\/\/hotelvisavis.net\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/hotelvisavis.net\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/11\/vis-a-vis-logo.svg\",\"contentUrl\":\"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/11\/vis-a-vis-logo.svg\",\"caption\":\"Vis \u00e0 Vis\"},\"image\":{\"@id\":\"https:\/\/hotelvisavis.net\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Hotel.Duchi.Trieste\",\"https:\/\/www.instagram.com\/duchitrieste\/\",\"https:\/\/www.linkedin.com\/company\/grand-hotel-duchi-d-aosta-harry-s-piccolo-bistr-trieste\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hotel im Zentrum von Triest | Hotel Vis A' Vis","description":"Einzigartiges Erlebnis in Triest. \u00dcbernachten Sie im Herzen der Stadt im Hotel Vis A' Vis. Entdecken Sie Komfort auf Knopfdruck!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/","og_locale":"de_DE","og_type":"article","og_title":"Hotel im Zentrum von Triest | Hotel Vis A' Vis","og_description":"Einzigartiges Erlebnis in Triest. \u00dcbernachten Sie im Herzen der Stadt im Hotel Vis A' Vis. Entdecken Sie Komfort auf Knopfdruck!","og_url":"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/","og_site_name":"Vis \u00e0 Vis","article_publisher":"https:\/\/www.facebook.com\/Hotel.Duchi.Trieste","article_modified_time":"2026-02-11T10:21:16+00:00","og_image":[{"width":2000,"height":1498,"url":"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/","url":"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/","name":"Hotel im Zentrum von Triest | Hotel Vis A' Vis","isPartOf":{"@id":"https:\/\/hotelvisavis.net\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/#primaryimage"},"image":{"@id":"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/#primaryimage"},"thumbnailUrl":"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel.webp","datePublished":"2023-12-27T21:32:27+00:00","dateModified":"2026-02-11T10:21:16+00:00","description":"Einzigartiges Erlebnis in Triest. \u00dcbernachten Sie im Herzen der Stadt im Hotel Vis A' Vis. Entdecken Sie Komfort auf Knopfdruck!","breadcrumb":{"@id":"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/#primaryimage","url":"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel.webp","contentUrl":"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel.webp","width":2000,"height":1498,"caption":"Vista aerea di una strada cittadina con parcheggio e edifici storici."},{"@type":"BreadcrumbList","@id":"https:\/\/hotelvisavis.net\/de\/hotel-zentrum-triest\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hotelvisavis.net\/de\/"},{"@type":"ListItem","position":2,"name":"Hotel"}]},{"@type":"WebSite","@id":"https:\/\/hotelvisavis.net\/de\/#website","url":"https:\/\/hotelvisavis.net\/de\/","name":"Vis \u00e0 Vis","description":"","publisher":{"@id":"https:\/\/hotelvisavis.net\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotelvisavis.net\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hotelvisavis.net\/de\/#organization","name":"Vis \u00e0 Vis","url":"https:\/\/hotelvisavis.net\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hotelvisavis.net\/de\/#\/schema\/logo\/image\/","url":"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/11\/vis-a-vis-logo.svg","contentUrl":"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/11\/vis-a-vis-logo.svg","caption":"Vis \u00e0 Vis"},"image":{"@id":"https:\/\/hotelvisavis.net\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Hotel.Duchi.Trieste","https:\/\/www.instagram.com\/duchitrieste\/","https:\/\/www.linkedin.com\/company\/grand-hotel-duchi-d-aosta-harry-s-piccolo-bistr-trieste\/"]}]}},"coauthors":[],"author_meta":{"author_link":"https:\/\/hotelvisavis.net\/de\/author\/jampaa\/","display_name":"Jampaa"},"relative_dates":{"created":"Posted 3\u00a0Jahren ago","modified":"Updated 5\u00a0Monaten ago"},"absolute_dates":{"created":"Posted on 27\/12\/2023","modified":"Updated on 11\/02\/2026"},"absolute_dates_time":{"created":"Posted on 27\/12\/2023 22:32","modified":"Updated on 11\/02\/2026 11:21"},"featured_img_caption":"","featured_img":"https:\/\/hotelvisavis.net\/wp-content\/uploads\/2023\/12\/Hotel-1568x1174.webp","series_order":"","_links":{"self":[{"href":"https:\/\/hotelvisavis.net\/de\/wp-json\/wp\/v2\/pages\/7652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelvisavis.net\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotelvisavis.net\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotelvisavis.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelvisavis.net\/de\/wp-json\/wp\/v2\/comments?post=7652"}],"version-history":[{"count":11,"href":"https:\/\/hotelvisavis.net\/de\/wp-json\/wp\/v2\/pages\/7652\/revisions"}],"predecessor-version":[{"id":9807,"href":"https:\/\/hotelvisavis.net\/de\/wp-json\/wp\/v2\/pages\/7652\/revisions\/9807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotelvisavis.net\/de\/wp-json\/wp\/v2\/media\/7121"}],"wp:attachment":[{"href":"https:\/\/hotelvisavis.net\/de\/wp-json\/wp\/v2\/media?parent=7652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}